{"id":162,"date":"2020-07-29T11:24:41","date_gmt":"2020-07-29T05:54:41","guid":{"rendered":"http:\/\/www.lifecareayurveda.com\/q2a\/gj\/contact-us-page\/"},"modified":"2020-12-13T13:36:28","modified_gmt":"2020-12-13T08:06:28","slug":"contact-us","status":"publish","type":"page","link":"https:\/\/www.lifecareayurveda.com\/q2a\/gj\/contact-us\/","title":{"rendered":"\u0a85\u0aae\u0abe\u0ab0\u0acb \u0ab8\u0a82\u0aaa\u0ab0\u0acd\u0a95 \u0a95\u0ab0\u0acb.."},"content":{"rendered":"<div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-364\"><form id=\"wpforms-form-364\" class=\"wpforms-validate wpforms-form\" data-formid=\"364\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/q2a\/gj\/wp-json\/wp\/v2\/pages\/162\" data-token=\"ff41ed1ef36656d8d44f057dea36769b\" data-token-time=\"1778683516\"><div class=\"wpforms-head-container\"><div class=\"wpforms-title\">\u0a85\u0aae\u0abe\u0ab0\u0acb \u0ab8\u0a82\u0aaa\u0ab0\u0acd\u0a95 \u0a95\u0ab0\u0acb..<\/div><\/div><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-364-field_0-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"0\"><label class=\"wpforms-field-label\">\u0a86\u0aaa\u0aa8\u0ac1\u0a82 \u0aa8\u0abe\u0aae <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-364-field_0\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][0][first]\" required><label for=\"wpforms-364-field_0\" class=\"wpforms-field-sublabel after\">First<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-364-field_0-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][0][last]\" required><label for=\"wpforms-364-field_0-last\" class=\"wpforms-field-sublabel after\">Last<\/label><\/div><\/div><\/div><div id=\"wpforms-364-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-364-field_1\">\u0a87-\u0aae\u0ac7\u0a87\u0ab2 <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-364-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" spellcheck=\"false\" required><\/div><div id=\"wpforms-364-field_3-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-364-field_3\">\u0aae\u0acb\u0aac\u0abe\u0a87\u0ab2 \u0aa8\u0a82\u0aac\u0ab0 <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"number\" id=\"wpforms-364-field_3\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][3]\" step=\"any\" required><\/div><div id=\"wpforms-364-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-364-field_2\">\u0a86\u0aaa\u0aa8\u0acb \u0ab8\u0a82\u0aa6\u0ac7\u0ab6 \u0a85\u0ab9\u0abf\u0a82 \u0a9c\u0aa3\u0abe\u0ab5\u0acb <span class=\"wpforms-required-label\">*<\/span><\/label><textarea id=\"wpforms-364-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" required><\/textarea><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-recaptcha-container wpforms-is-recaptcha wpforms-is-recaptcha-type-v2\" ><div class=\"g-recaptcha\" data-sitekey=\"6LdhitoSAAAAACQ6j9HOiMmNKO4BwvgIR-vXaO5s\"><\/div><input type=\"text\" name=\"g-recaptcha-hidden\" class=\"wpforms-recaptcha-hidden\" style=\"position:absolute!important;clip:rect(0,0,0,0)!important;height:1px!important;width:1px!important;border:0!important;overflow:hidden!important;padding:0!important;margin:0!important;\" data-rule-recaptcha=\"1\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"364\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/www.lifecareayurveda.com\/q2a\/gj\/wp-json\/wp\/v2\/pages\/162\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-364\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Submit\" aria-live=\"assertive\" value=\"wpforms-submit\">Submit<\/button><\/div><\/form><\/div>  <!-- .wpforms-container -->\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_stc_notifier_status":"","_stc_notifier_sent_time":"","_stc_notifier_request":false,"_stc_notifier_prevent":false,"_stc_subscriber_keywords":"","_stc_subscriber_search_areas":"","footnotes":""},"class_list":["post-162","page","type-page","status-publish","hentry"],"aioseo_notices":[],"jetpack_likes_enabled":true,"jetpack-related-posts":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/PceWAE-2C","_links":{"self":[{"href":"https:\/\/www.lifecareayurveda.com\/q2a\/gj\/wp-json\/wp\/v2\/pages\/162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lifecareayurveda.com\/q2a\/gj\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.lifecareayurveda.com\/q2a\/gj\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.lifecareayurveda.com\/q2a\/gj\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lifecareayurveda.com\/q2a\/gj\/wp-json\/wp\/v2\/comments?post=162"}],"version-history":[{"count":10,"href":"https:\/\/www.lifecareayurveda.com\/q2a\/gj\/wp-json\/wp\/v2\/pages\/162\/revisions"}],"predecessor-version":[{"id":365,"href":"https:\/\/www.lifecareayurveda.com\/q2a\/gj\/wp-json\/wp\/v2\/pages\/162\/revisions\/365"}],"wp:attachment":[{"href":"https:\/\/www.lifecareayurveda.com\/q2a\/gj\/wp-json\/wp\/v2\/media?parent=162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}